{"id":625,"date":"2024-07-24T23:07:32","date_gmt":"2024-07-25T02:07:32","guid":{"rendered":"https:\/\/millerdantas.com\/blog\/?p=625"},"modified":"2024-07-25T00:04:01","modified_gmt":"2024-07-25T03:04:01","slug":"leben-dia-38","status":"publish","type":"post","link":"https:\/\/millerdantas.com\/blog\/2024\/07\/24\/leben-dia-38\/","title":{"rendered":"Leben dia 38"},"content":{"rendered":"<h1>Voltei pro desenvolvimento do Leben&#8230;<\/h1>\n<p>Vai ano, volta ano e sempre pego esse projeto, toco por alguns dias e paro.<\/p>\n<p>Hoje eu cansei de usar o godot, estava na vers\u00e3o v3.3.2.<\/p>\n<p>estive fazendo o upgrade do projeto pra vers\u00e3o v4.2.2, mudou bastante coisa, acabou que eu tive que portar o Leben.Core pra net core 6.0<\/p>\n<p>terminei de portar e comecei trabalhar no projeto<br \/>\nVira e mexe vem o erro:<br \/>\n<a class=\"wp-editor-md-post-content-link\" href=\"https:\/\/millerdantas.com\/blog\/wp-content\/uploads\/2024\/07\/wp_editor_md_32f0fc41fb77e583f960a926af63eeae.jpg\"><img decoding=\"async\" src=\"https:\/\/millerdantas.com\/blog\/wp-content\/uploads\/2024\/07\/wp_editor_md_32f0fc41fb77e583f960a926af63eeae.jpg\" alt=\"\" \/><\/a><\/p>\n<p>eu deleto o script, mudo o script, crio um novo, mas nunca \u00e9 uma coisa simples, parece que foi uma gambiarra pra funcionar C# nessa engine.<\/p>\n<p>por conta disso vou mudar de engine de novo&#8230;<br \/>\npra quem n\u00e3o viu o hist\u00f3rico&#8230;<\/p>\n<p>eu comecei o projeto com Unity, foi pro Mono, Unreal, tentei zenko\/stride.<\/p>\n<p>Voltarei pro Mono que j\u00e1 tem um ecossistema mais pr\u00f3ximo do que quero trabalhar<\/p>\n<p>eu estou tentando ir desenvolvendo com BDD ent\u00e3o eu n\u00e3o preciso de uma Engine ainda<\/p>\n<p>s\u00f3 quero adicionar os objetos programaticamente e rodar pelo Leben.Core.<\/p>\n<p>estou indo por essa abordagem porque quero ter a possibilidade de ter Full mod support, sendo poss\u00edvel algu\u00e9m se quiser re-escrever como a IA funciona.<\/p>\n<p>mas essas engines s\u00e3o muito travadas&#8230;<\/p>\n<p>era isso<\/p>\n<p>Esteja Curioso!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voltei pro desenvolvimento do Leben&#8230; Vai ano, volta ano e sempre pego esse projeto, toco por alguns dias e paro. Hoje eu cansei de usar o godot, estava na vers\u00e3o v3.3.2. estive fazendo o upgrade do projeto pra vers\u00e3o v4.2.2, mudou bastante coisa, acabou que eu tive que portar o Leben.Core pra net core 6.0 &hellip; <a href=\"https:\/\/millerdantas.com\/blog\/2024\/07\/24\/leben-dia-38\/\" class=\"more-link\">Continue lendo <span class=\"screen-reader-text\">Leben dia 38<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-625","post","type-post","status-publish","format-standard","hentry","category-leben-project"],"_links":{"self":[{"href":"https:\/\/millerdantas.com\/blog\/wp-json\/wp\/v2\/posts\/625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/millerdantas.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/millerdantas.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/millerdantas.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/millerdantas.com\/blog\/wp-json\/wp\/v2\/comments?post=625"}],"version-history":[{"count":3,"href":"https:\/\/millerdantas.com\/blog\/wp-json\/wp\/v2\/posts\/625\/revisions"}],"predecessor-version":[{"id":628,"href":"https:\/\/millerdantas.com\/blog\/wp-json\/wp\/v2\/posts\/625\/revisions\/628"}],"wp:attachment":[{"href":"https:\/\/millerdantas.com\/blog\/wp-json\/wp\/v2\/media?parent=625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/millerdantas.com\/blog\/wp-json\/wp\/v2\/categories?post=625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/millerdantas.com\/blog\/wp-json\/wp\/v2\/tags?post=625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}